{"id":1915,"date":"2025-05-08T14:34:22","date_gmt":"2025-05-08T19:34:22","guid":{"rendered":"https:\/\/www.textildelvalle.pe\/es\/?p=1915"},"modified":"2025-05-08T14:34:23","modified_gmt":"2025-05-08T19:34:23","slug":"informe-de-gestion-bic-2024","status":"publish","type":"post","link":"https:\/\/www.textildelvalle.pe\/es\/2025\/05\/08\/informe-de-gestion-bic-2024\/","title":{"rendered":"Informe de Gesti\u00f3n BIC 2024"},"content":{"rendered":"\n<p>Como parte del compromiso de Textil Del Valle como una Sociedad de Beneficio e Inter\u00e9s Colectivo (BIC), publicamos nuestro Informe de Gesti\u00f3n BIC 2024, en donde detallamos nuestra contribuci\u00f3n con diversos proyectos de impacto local y regional en criterios ASG (ambiental, econ\u00f3mica y social).<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.textildelvalle.pe\/es\/wp-content\/uploads\/2025\/05\/Informe-de-gestion-BIC-Textil-del-Valle-TDV.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Informe de gesti\u00f3n BIC Textil del Valle (TDV).\"><\/object><a id=\"wp-block-file--media-a020e153-907a-42be-80de-886f76cc5b02\" href=\"https:\/\/www.textildelvalle.pe\/es\/wp-content\/uploads\/2025\/05\/Informe-de-gestion-BIC-Textil-del-Valle-TDV.pdf\">Informe de gesti\u00f3n BIC Textil del Valle (TDV)<\/a><a href=\"https:\/\/www.textildelvalle.pe\/es\/wp-content\/uploads\/2025\/05\/Informe-de-gestion-BIC-Textil-del-Valle-TDV.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-a020e153-907a-42be-80de-886f76cc5b02\">Descarga<\/a><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte del compromiso de Textil Del Valle como una Sociedad de Beneficio e Inter\u00e9s Colectivo (BIC), publicamos nuestro Informe de Gesti\u00f3n BIC 2024, en donde detallamos nuestra contribuci\u00f3n con diversos proyectos de impacto local y regional en criterios ASG (ambiental, econ\u00f3mica y social).<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1915","post","type-post","status-publish","format-standard","hentry","category-sostenibilidad"],"_links":{"self":[{"href":"https:\/\/www.textildelvalle.pe\/es\/wp-json\/wp\/v2\/posts\/1915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.textildelvalle.pe\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.textildelvalle.pe\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.textildelvalle.pe\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.textildelvalle.pe\/es\/wp-json\/wp\/v2\/comments?post=1915"}],"version-history":[{"count":1,"href":"https:\/\/www.textildelvalle.pe\/es\/wp-json\/wp\/v2\/posts\/1915\/revisions"}],"predecessor-version":[{"id":1917,"href":"https:\/\/www.textildelvalle.pe\/es\/wp-json\/wp\/v2\/posts\/1915\/revisions\/1917"}],"wp:attachment":[{"href":"https:\/\/www.textildelvalle.pe\/es\/wp-json\/wp\/v2\/media?parent=1915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.textildelvalle.pe\/es\/wp-json\/wp\/v2\/categories?post=1915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.textildelvalle.pe\/es\/wp-json\/wp\/v2\/tags?post=1915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}